{"id":22397,"date":"2024-02-19T18:54:24","date_gmt":"2024-02-19T15:54:24","guid":{"rendered":"https:\/\/moodnesskw.com\/?post_type=product&#038;p=22397"},"modified":"2025-02-14T02:14:06","modified_gmt":"2025-02-13T23:14:06","slug":"gebaire-x-metallic","status":"publish","type":"product","link":"https:\/\/moodnesskw.com\/ar\/product\/gebaire-x-metallic\/","title":{"rendered":"Gebaire X metallic"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":22395,"comment_status":"open","ping_status":"closed","template":"","meta":{"nf_dc_page":"","_joinchat":[]},"product_brand":[],"product_cat":[183],"product_tag":[],"class_list":["post-22397","product","type-product","status-publish","has-post-thumbnail","product_cat-shop-all","first","instock","shipping-taxable","purchasable","product-type-variable"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Gebaire X metallic | MOODness<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/moodnesskw.com\/ar\/product\/gebaire-x-metallic\/\" \/>\n<meta property=\"og:locale\" content=\"ar_AR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Gebaire X metallic | MOODness\" \/>\n<meta property=\"og:url\" content=\"https:\/\/moodnesskw.com\/ar\/product\/gebaire-x-metallic\/\" \/>\n<meta property=\"og:site_name\" content=\"MOODness\" \/>\n<meta property=\"article:modified_time\" content=\"2025-02-13T23:14:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/moodnesskw.com\/wp-content\/uploads\/2024\/02\/IMG_5719-768x1024.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"768\" \/>\n\t<meta property=\"og:image:height\" content=\"1024\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/moodnesskw.com\\\/product\\\/gebaire-x-metallic\\\/\",\"url\":\"https:\\\/\\\/moodnesskw.com\\\/product\\\/gebaire-x-metallic\\\/\",\"name\":\"Gebaire X metallic | MOODness\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/moodnesskw.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/moodnesskw.com\\\/product\\\/gebaire-x-metallic\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/moodnesskw.com\\\/product\\\/gebaire-x-metallic\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/moodnesskw.com\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/IMG_5719-scaled.jpeg?fit=1920%2C2560&ssl=1\",\"datePublished\":\"2024-02-19T15:54:24+00:00\",\"dateModified\":\"2025-02-13T23:14:06+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/moodnesskw.com\\\/product\\\/gebaire-x-metallic\\\/#breadcrumb\"},\"inLanguage\":\"ar\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/moodnesskw.com\\\/product\\\/gebaire-x-metallic\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ar\",\"@id\":\"https:\\\/\\\/moodnesskw.com\\\/product\\\/gebaire-x-metallic\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/moodnesskw.com\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/IMG_5719-scaled.jpeg?fit=1920%2C2560&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/moodnesskw.com\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/IMG_5719-scaled.jpeg?fit=1920%2C2560&ssl=1\",\"width\":1920,\"height\":2560},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/moodnesskw.com\\\/product\\\/gebaire-x-metallic\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/moodnesskw.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/moodnesskw.com\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Gebaire X metallic\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/moodnesskw.com\\\/#website\",\"url\":\"https:\\\/\\\/moodnesskw.com\\\/\",\"name\":\"MOODness\",\"description\":\"Elegant Fashion Brand\",\"publisher\":{\"@id\":\"https:\\\/\\\/moodnesskw.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/moodnesskw.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ar\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/moodnesskw.com\\\/#organization\",\"name\":\"MOODness\",\"url\":\"https:\\\/\\\/moodnesskw.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ar\",\"@id\":\"https:\\\/\\\/moodnesskw.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/moodnesskw.com\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/Black-color-logo.png?fit=412%2C157&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/moodnesskw.com\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/Black-color-logo.png?fit=412%2C157&ssl=1\",\"width\":412,\"height\":157,\"caption\":\"MOODness\"},\"image\":{\"@id\":\"https:\\\/\\\/moodnesskw.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.instagram.com\\\/moodness.kw\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Gebaire X metallic | MOODness","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/moodnesskw.com\/ar\/product\/gebaire-x-metallic\/","og_locale":"ar_AR","og_type":"article","og_title":"Gebaire X metallic | MOODness","og_url":"https:\/\/moodnesskw.com\/ar\/product\/gebaire-x-metallic\/","og_site_name":"MOODness","article_modified_time":"2025-02-13T23:14:06+00:00","og_image":[{"width":768,"height":1024,"url":"https:\/\/moodnesskw.com\/wp-content\/uploads\/2024\/02\/IMG_5719-768x1024.jpeg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/moodnesskw.com\/product\/gebaire-x-metallic\/","url":"https:\/\/moodnesskw.com\/product\/gebaire-x-metallic\/","name":"Gebaire X metallic | MOODness","isPartOf":{"@id":"https:\/\/moodnesskw.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/moodnesskw.com\/product\/gebaire-x-metallic\/#primaryimage"},"image":{"@id":"https:\/\/moodnesskw.com\/product\/gebaire-x-metallic\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/moodnesskw.com\/wp-content\/uploads\/2024\/02\/IMG_5719-scaled.jpeg?fit=1920%2C2560&ssl=1","datePublished":"2024-02-19T15:54:24+00:00","dateModified":"2025-02-13T23:14:06+00:00","breadcrumb":{"@id":"https:\/\/moodnesskw.com\/product\/gebaire-x-metallic\/#breadcrumb"},"inLanguage":"ar","potentialAction":[{"@type":"ReadAction","target":["https:\/\/moodnesskw.com\/product\/gebaire-x-metallic\/"]}]},{"@type":"ImageObject","inLanguage":"ar","@id":"https:\/\/moodnesskw.com\/product\/gebaire-x-metallic\/#primaryimage","url":"https:\/\/i0.wp.com\/moodnesskw.com\/wp-content\/uploads\/2024\/02\/IMG_5719-scaled.jpeg?fit=1920%2C2560&ssl=1","contentUrl":"https:\/\/i0.wp.com\/moodnesskw.com\/wp-content\/uploads\/2024\/02\/IMG_5719-scaled.jpeg?fit=1920%2C2560&ssl=1","width":1920,"height":2560},{"@type":"BreadcrumbList","@id":"https:\/\/moodnesskw.com\/product\/gebaire-x-metallic\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/moodnesskw.com\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/moodnesskw.com\/shop\/"},{"@type":"ListItem","position":3,"name":"Gebaire X metallic"}]},{"@type":"WebSite","@id":"https:\/\/moodnesskw.com\/#website","url":"https:\/\/moodnesskw.com\/","name":"MOODness","description":"Elegant Fashion Brand","publisher":{"@id":"https:\/\/moodnesskw.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/moodnesskw.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ar"},{"@type":"Organization","@id":"https:\/\/moodnesskw.com\/#organization","name":"MOODness","url":"https:\/\/moodnesskw.com\/","logo":{"@type":"ImageObject","inLanguage":"ar","@id":"https:\/\/moodnesskw.com\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/moodnesskw.com\/wp-content\/uploads\/2021\/11\/Black-color-logo.png?fit=412%2C157&ssl=1","contentUrl":"https:\/\/i0.wp.com\/moodnesskw.com\/wp-content\/uploads\/2021\/11\/Black-color-logo.png?fit=412%2C157&ssl=1","width":412,"height":157,"caption":"MOODness"},"image":{"@id":"https:\/\/moodnesskw.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.instagram.com\/moodness.kw\/"]}]}},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/moodnesskw.com\/ar\/wp-json\/wp\/v2\/product\/22397","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/moodnesskw.com\/ar\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/moodnesskw.com\/ar\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/moodnesskw.com\/ar\/wp-json\/wp\/v2\/comments?post=22397"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/moodnesskw.com\/ar\/wp-json\/wp\/v2\/media\/22395"}],"wp:attachment":[{"href":"https:\/\/moodnesskw.com\/ar\/wp-json\/wp\/v2\/media?parent=22397"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/moodnesskw.com\/ar\/wp-json\/wp\/v2\/product_brand?post=22397"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/moodnesskw.com\/ar\/wp-json\/wp\/v2\/product_cat?post=22397"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/moodnesskw.com\/ar\/wp-json\/wp\/v2\/product_tag?post=22397"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}